{"id":8056,"date":"2025-10-01T09:59:30","date_gmt":"2025-10-01T12:59:30","guid":{"rendered":"https:\/\/compartilhabahia.com.br\/?p=8056"},"modified":"2025-10-01T10:00:26","modified_gmt":"2025-10-01T13:00:26","slug":"empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari","status":"publish","type":"post","link":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/","title":{"rendered":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong><em>Um exerc\u00edcio simulado presencial para controle de emerg\u00eancia est\u00e1 sendo realizado neste momento (9:00 do dia 1\u00ba\/10\/2025) no Polo Industrial de Cama\u00e7ari. Cerca de 15 mil trabalhadores diretos e contratados de mais de 50 empresas que operam no Complexo Industrial participam do treinamento.<\/em><\/strong><\/p>\n\n\n\n<p>Um exerc\u00edcio simulado est\u00e1 sendo realizado neste momento no Polo industrial de Cama\u00e7ari. Coordenado pelo Cofic \u2013 Comit\u00ea de Fomento Industrial de Cama\u00e7ari e Braskem Q1, o treinamento tem por objetivo testar, avaliar e aprimorar os procedimentos coletivos de seguran\u00e7a do Complexo Industrial, especialmente no que tange ao acionamento e utiliza\u00e7\u00e3o dos recursos&nbsp;t\u00e9cnicos dispon\u00edveis do Plano de Aux\u00edlio M\u00fatuo \u2013 PAM e do Plano de Atendimento M\u00e9dico Emerg\u00eancia &#8211; PAME, para controle de situa\u00e7\u00f5es de emerg\u00eancia.<\/p>\n\n\n\n<p>O treinamento teve in\u00edcio em local pr\u00f3ximo da Braskem Q1, com&nbsp;simula\u00e7\u00e3o de um de uma emerg\u00eancia de alto risco (vazamento de produto qu\u00edmico, seguido de explos\u00e3o e inc\u00eandio&nbsp;em um duto de uma das tubovias do Complexo B\u00e1sico Polo).&nbsp;Os&nbsp;alarmes de seguran\u00e7a foram acionados e as primeiras a\u00e7\u00f5es para controle da \u201cemerg\u00eancia\u201d est\u00e3o sendo coordenadas pela pr\u00f3pria Braskem Q1 que, em seguida acionar\u00e1, por r\u00e1dio, o Plano de Aux\u00edlio M\u00fatuo do Polo (PAM) e o PAME \u2013 Plano de Atendimento M\u00e9dico em Emerg\u00eancia, solicitando ajuda das demais empresas que operam no Complexo&nbsp;Industrial.<\/p>\n\n\n\n<p>Por se tratar de uma \u201cemerg\u00eancia\u201d de grande porte,&nbsp;a Braskem Q1, fornecedora de mat\u00e9rias primas e utilidades no Polo de Cama\u00e7ari,&nbsp;proceder\u00e1 \u00e0 evas\u00e3o dos seus empregados para pontos de encontro seguro, solicitando \u00e0s demais empresas do complexo industrial que adotem o mesmo procedimento. Cerca de 15 mil pessoas, entre empregados diretos e contratados, ser\u00e3o orientados por profissionais de seguran\u00e7a&nbsp;e coordenadores de evas\u00e3o, deslocando-se a p\u00e9 para os pontos seguros distribu\u00eddos em v\u00e1rios locais do Complexo Industrial, onde permanecer\u00e3o at\u00e9 o final da emerg\u00eancia.<\/p>\n\n\n\n<p><strong>BLOQUEIO DE VIAS<\/strong><\/p>\n\n\n\n<p>Para maior seguran\u00e7a das pessoas envolvidas no exerc\u00edcio simulado e facilidade de deslocamento das viaturas de combate a inc\u00eandio e ambul\u00e2ncias, as vias de acesso ao Polo (Axial, Parafuso, Canal de Tr\u00e1fego, Liga\u00e7\u00e3o, Perimetral e Frontal) estar\u00e3o bloqueadas at\u00e9 as 11h30min.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o envolve mais de 150&nbsp;t\u00e9cnicos, brigadistas e profissionais da \u00e1rea m\u00e9dica, 30 viaturas de combate a inc\u00eandio, 20 ambul\u00e2ncias.&nbsp;Conta ainda com o apoio da Pol\u00edcia Militar (12\u00ba Batalh\u00e3o, 36\u00aa Companhia de Pol\u00edcia e Companhia Independente de Policiamento Especializado &#8211; CIPE), Pol\u00edcia Rodovi\u00e1ria Estadual, Samu, Sistema de controle de Tr\u00e2nsito de Cama\u00e7ari, Corpo de Bombeiros, representes do Conselho Comunit\u00e1rio de Cama\u00e7ari e Dias D\u00b4\u00c1vila e do Nudec \u2013 N\u00facleo de Defesa Comunit\u00e1ria,&nbsp; Defesa Civil dos dois munic\u00edpios, dentre outros envolvidos.<\/p>\n\n\n\n<p>Este \u00e9 o vig\u00e9simo sexto exerc\u00edcio simulado de evas\u00e3o geral das empresas do Polo e o vig\u00e9simo promovido&nbsp;sem aviso pr\u00e9vio. Ao longo do ano, treinamentos similares s\u00e3o realizados individualmente pelas empresas ou grupo de empresas vizinhas, com o mesmo prop\u00f3sito de avaliar o funcionamento dos sistemas de seguran\u00e7a, procedimentos, sistemas de comunica\u00e7\u00e3o e n\u00edvel de entrosamento das equipes t\u00e9cnicas para controle de emerg\u00eancia no Polo.<\/p>\n\n\n\n<p>O Polo de Cama\u00e7ari&nbsp;investe em m\u00e9dia R$ 100 milh\u00f5es anualmente em&nbsp;seguran\u00e7a industrial, incluindo aquisi\u00e7\u00e3o de viaturas de combate a inc\u00eandio, ambul\u00e2ncias, treinamento de pessoal, monitoramento ambiental, Equipamentos de Prote\u00e7\u00e3o Individual, melhoria nos servi\u00e7os de atendimento m\u00e9dico de emerg\u00eancia, dentre outros itens. A preven\u00e7\u00e3o de acidentes \u00e9 uma das prioridades do Complexo Industrial, que estimula a atua\u00e7\u00e3o integrada das \u00e1reas de seguran\u00e7a, sa\u00fade e meio ambiente para o controle de emerg\u00eancias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um exerc\u00edcio simulado presencial para controle de emerg\u00eancia est\u00e1 sendo realizado neste momento (9:00 do dia 1\u00ba\/10\/2025) no Polo Industrial de Cama\u00e7ari. Cerca de 15 mil trabalhadores diretos e contratados de mais de 50 empresas que operam no Complexo Industrial participam do treinamento. Um exerc\u00edcio simulado est\u00e1 sendo realizado neste momento no Polo industrial de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-8056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camacari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia\" \/>\n<meta property=\"og:description\" content=\"Um exerc\u00edcio simulado presencial para controle de emerg\u00eancia est\u00e1 sendo realizado neste momento (9:00 do dia 1\u00ba\/10\/2025) no Polo Industrial de Cama\u00e7ari. Cerca de 15 mil trabalhadores diretos e contratados de mais de 50 empresas que operam no Complexo Industrial participam do treinamento. Um exerc\u00edcio simulado est\u00e1 sendo realizado neste momento no Polo industrial de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\" \/>\n<meta property=\"og:site_name\" content=\"Compartilha Bahia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/compartilhabahia\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-01T12:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-01T13:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/10\/Foto-geral-do-Polo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\"},\"headline\":\"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI\",\"datePublished\":\"2025-10-01T12:59:30+00:00\",\"dateModified\":\"2025-10-01T13:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\"},\"wordCount\":672,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"articleSection\":[\"Cama\u00e7ari\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\",\"name\":\"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\"},\"datePublished\":\"2025-10-01T12:59:30+00:00\",\"dateModified\":\"2025-10-01T13:00:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/compartilhabahia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"name\":\"Compartilha Bahia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compartilhabahia.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\",\"name\":\"Compartilha Bahia\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"contentUrl\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"width\":300,\"height\":106,\"caption\":\"Compartilha Bahia\"},\"image\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/compartilhabahia\",\"https:\/\/www.instagram.com\/compartilhabahia\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/compartilhabahia.com.br\"],\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/","og_locale":"pt_BR","og_type":"article","og_title":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia","og_description":"Um exerc\u00edcio simulado presencial para controle de emerg\u00eancia est\u00e1 sendo realizado neste momento (9:00 do dia 1\u00ba\/10\/2025) no Polo Industrial de Cama\u00e7ari. Cerca de 15 mil trabalhadores diretos e contratados de mais de 50 empresas que operam no Complexo Industrial participam do treinamento. Um exerc\u00edcio simulado est\u00e1 sendo realizado neste momento no Polo industrial de [&hellip;]","og_url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/","og_site_name":"Compartilha Bahia","article_publisher":"https:\/\/web.facebook.com\/compartilhabahia","article_published_time":"2025-10-01T12:59:30+00:00","article_modified_time":"2025-10-01T13:00:26+00:00","og_image":[{"width":2560,"height":1656,"url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/10\/Foto-geral-do-Polo-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#article","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/"},"author":{"name":"admin","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04"},"headline":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI","datePublished":"2025-10-01T12:59:30+00:00","dateModified":"2025-10-01T13:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/"},"wordCount":672,"commentCount":0,"publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"articleSection":["Cama\u00e7ari"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/","url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/","name":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI - Compartilha Bahia","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/#website"},"datePublished":"2025-10-01T12:59:30+00:00","dateModified":"2025-10-01T13:00:26+00:00","breadcrumb":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/10\/01\/empresas-realizam-exercicio-simulado-no-polo-industrial-de-camacari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/compartilhabahia.com.br\/"},{"@type":"ListItem","position":2,"name":"EMPRESAS REALIZAM EXERC\u00cdCIO SIMULADO NO POLO INDUSTRIAL DE CAMA\u00c7ARI"}]},{"@type":"WebSite","@id":"https:\/\/compartilhabahia.com.br\/#website","url":"https:\/\/compartilhabahia.com.br\/","name":"Compartilha Bahia","description":"","publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compartilhabahia.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/compartilhabahia.com.br\/#organization","name":"Compartilha Bahia","url":"https:\/\/compartilhabahia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","contentUrl":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","width":300,"height":106,"caption":"Compartilha Bahia"},"image":{"@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/compartilhabahia","https:\/\/www.instagram.com\/compartilhabahia\/"]},{"@type":"Person","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/compartilhabahia.com.br"],"url":"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/"}]}},"_links":{"self":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8056"}],"version-history":[{"count":1,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8056\/revisions"}],"predecessor-version":[{"id":8058,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8056\/revisions\/8058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/8057"}],"wp:attachment":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}