{"id":7908,"date":"2025-09-17T13:51:42","date_gmt":"2025-09-17T16:51:42","guid":{"rendered":"https:\/\/compartilhabahia.com.br\/?p=7908"},"modified":"2025-09-17T21:15:31","modified_gmt":"2025-09-18T00:15:31","slug":"secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro","status":"publish","type":"post","link":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/","title":{"rendered":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A secret\u00e1ria de governo de Cama\u00e7ari, Ednalva Santana, a Branca, liderou na manh\u00e3 desta ter\u00e7a-feira (16), uma reuni\u00e3o de secret\u00e1rios municipais, para realizar uma avalia\u00e7\u00e3o sobre os desfiles c\u00edvicos que aconteceram nos distritos de Monte Gordo e Vila de Abrantes, bem como para finalizar os preparativos para o grande desfile de 28 de setembro, data em que se comemora o anivers\u00e1rio da cidade.<\/p>\n\n\n\n<p>\u201cNesta manh\u00e3, nos reunimos para avaliar os desfiles de Monte Gordo e Abrantes e alinhar os \u00faltimos detalhes para o grande desfile do dia 28, para celebra\u00e7\u00e3o do anivers\u00e1rio da nossa Cama\u00e7ari! Seguimos juntos nesse compromisso de fazer sempre o melhor pela nossa cidade e por cada pessoa que faz parte dela.\u201d Disse Branca em seu perfil na rede social.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1-1024x602.jpeg\" alt=\"\" class=\"wp-image-7910\" srcset=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1-1024x602.jpeg 1024w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1-300x176.jpeg 300w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1-768x451.jpeg 768w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1-1536x902.jpeg 1536w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-17-at-13.16.48-1.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Como foram os desfiles:<\/p>\n\n\n\n<p>No domingo (14) pela manh\u00e3, abrindo o calend\u00e1rio de comemora\u00e7\u00f5es pelos 267 anos de emancipa\u00e7\u00e3o pol\u00edtica de Cama\u00e7ari \u2013 celebrados em 28 de setembro \u2013, a Rua Bom Jesus, em Monte Gordo, foi tomada, por cores, sons e ritmos. Estudantes, bandas, fanfarras e grupos culturais deram vida ao tradicional desfile c\u00edvico, marcado por simbolismo hist\u00f3rico e tradi\u00e7\u00e3o, mas tamb\u00e9m por emo\u00e7\u00e3o e pertencimento.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o come\u00e7ou com a solenidade de hasteamento das bandeiras. O prefeito Luiz Caetano i\u00e7ou a bandeira do Brasil; o comandante da 59\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), Major F\u00e1bio Luiz Magalh\u00e3es, hasteou a da Bahia; e o presidente da C\u00e2mara Municipal, vereador Niltinho Maturino, a de Cama\u00e7ari. A cerim\u00f4nia foi acompanhada pela execu\u00e7\u00e3o dos hinos oficiais, interpretados pela Filarm\u00f4nica 28 de Setembro, num momento que refor\u00e7ou o orgulho e o civismo da cidade.<\/p>\n\n\n\n<p>Durante o ato, o prefeito Caetano destacou que as comemora\u00e7\u00f5es v\u00e3o al\u00e9m dos desfiles, pois refletem o processo de transforma\u00e7\u00e3o que Cama\u00e7ari tem vivenciado.<\/p>\n\n\n\n<p>\u201cEstamos trabalhando para fazer a mudan\u00e7a na sede, na orla e na zona rural. Estamos construindo pol\u00edticas p\u00fablicas em diversos setores, como na sa\u00fade \u2013 exemplo disso foi a reabertura, esta semana, do [Pronto Atendimento] PA de Monte Gordo, totalmente reestruturado e reorganizado. Por aqui tamb\u00e9m fizemos melhorias na ilumina\u00e7\u00e3o p\u00fablica, entre outras a\u00e7\u00f5es que elevam a qualidade de vida do nosso povo. E esse \u00e9 o verdadeiro sentido da comemora\u00e7\u00e3o: Cama\u00e7ari evolui, e com isso temos um povo cada vez mais feliz\u201d, afirmou.<\/p>\n\n\n\n<p>\u00c0 tarde, no mesmo domingo (14), com as arquibancadas lotadas e os entornos da Rua Vieira de Melo repletos de pessoas, o tradicional desfile c\u00edvico-cultural foi realizado em Vila de Abrantes, come\u00e7ando com o pelot\u00e3o de bandeiras do Brasil, da Bahia e de Cama\u00e7ari. Na sequ\u00eancia, a Filarm\u00f4nica 28 de Setembro deu o tom musical ao cortejo celebrativo, seguido pela marcha sincronizada do Batalh\u00e3o do Tiro de Guerra, da Pol\u00edcia Militar, Defesa Civil e do grupo Desbravadores.<br><br>\u201cCama\u00e7ari \u00e9 marcada por pessoas apaixonadas por esta terra. O desfile mostra a alma viva da popula\u00e7\u00e3o, representada pelas crian\u00e7as, pelos jovens, nos movimentos culturais, nos estudantes, em tudo\u201d, enfatizou o prefeito Luiz Caetano.<br><br>Sob organiza\u00e7\u00e3o da Secretaria de Educa\u00e7\u00e3o (Seduc), o desfile trouxe o tema \u201cCama\u00e7ari Educadora: cuidados que inspiram e reconectam pessoas\u201d. Estudantes e educadores de sete escolas da rede p\u00fablica municipal brilharam na avenida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A secret\u00e1ria de governo de Cama\u00e7ari, Ednalva Santana, a Branca, liderou na manh\u00e3 desta ter\u00e7a-feira (16), uma reuni\u00e3o de secret\u00e1rios municipais, para realizar uma avalia\u00e7\u00e3o sobre os desfiles c\u00edvicos que aconteceram nos distritos de Monte Gordo e Vila de Abrantes, bem como para finalizar os preparativos para o grande desfile de 28 de setembro, data [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-7908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camacari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia\" \/>\n<meta property=\"og:description\" content=\"A secret\u00e1ria de governo de Cama\u00e7ari, Ednalva Santana, a Branca, liderou na manh\u00e3 desta ter\u00e7a-feira (16), uma reuni\u00e3o de secret\u00e1rios municipais, para realizar uma avalia\u00e7\u00e3o sobre os desfiles c\u00edvicos que aconteceram nos distritos de Monte Gordo e Vila de Abrantes, bem como para finalizar os preparativos para o grande desfile de 28 de setembro, data [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Compartilha Bahia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/compartilhabahia\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T16:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T00:15:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/brabcareuniao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"946\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\"},\"headline\":\"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro\",\"datePublished\":\"2025-09-17T16:51:42+00:00\",\"dateModified\":\"2025-09-18T00:15:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\"},\"wordCount\":587,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"articleSection\":[\"Cama\u00e7ari\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\",\"name\":\"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\"},\"datePublished\":\"2025-09-17T16:51:42+00:00\",\"dateModified\":\"2025-09-18T00:15:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/compartilhabahia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"name\":\"Compartilha Bahia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compartilhabahia.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\",\"name\":\"Compartilha Bahia\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"contentUrl\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"width\":300,\"height\":106,\"caption\":\"Compartilha Bahia\"},\"image\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/compartilhabahia\",\"https:\/\/www.instagram.com\/compartilhabahia\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/compartilhabahia.com.br\"],\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/","og_locale":"pt_BR","og_type":"article","og_title":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia","og_description":"A secret\u00e1ria de governo de Cama\u00e7ari, Ednalva Santana, a Branca, liderou na manh\u00e3 desta ter\u00e7a-feira (16), uma reuni\u00e3o de secret\u00e1rios municipais, para realizar uma avalia\u00e7\u00e3o sobre os desfiles c\u00edvicos que aconteceram nos distritos de Monte Gordo e Vila de Abrantes, bem como para finalizar os preparativos para o grande desfile de 28 de setembro, data [&hellip;]","og_url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/","og_site_name":"Compartilha Bahia","article_publisher":"https:\/\/web.facebook.com\/compartilhabahia","article_published_time":"2025-09-17T16:51:42+00:00","article_modified_time":"2025-09-18T00:15:31+00:00","og_image":[{"width":946,"height":556,"url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/brabcareuniao.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#article","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/"},"author":{"name":"admin","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04"},"headline":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro","datePublished":"2025-09-17T16:51:42+00:00","dateModified":"2025-09-18T00:15:31+00:00","mainEntityOfPage":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/"},"wordCount":587,"commentCount":0,"publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"articleSection":["Cama\u00e7ari"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/","url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/","name":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro - Compartilha Bahia","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/#website"},"datePublished":"2025-09-17T16:51:42+00:00","dateModified":"2025-09-18T00:15:31+00:00","breadcrumb":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/17\/secretaria-de-governo-lidera-reuniao-do-secretariado-para-avaliar-desfiles-de-monte-gordo-e-abrantes-bem-como-preparar-o-28-de-setembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/compartilhabahia.com.br\/"},{"@type":"ListItem","position":2,"name":"Secret\u00e1ria de governo lidera reuni\u00e3o do secretariado para avaliar desfiles de Monte Gordo e Abrantes, bem como preparar o 28 de Setembro"}]},{"@type":"WebSite","@id":"https:\/\/compartilhabahia.com.br\/#website","url":"https:\/\/compartilhabahia.com.br\/","name":"Compartilha Bahia","description":"","publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compartilhabahia.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/compartilhabahia.com.br\/#organization","name":"Compartilha Bahia","url":"https:\/\/compartilhabahia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","contentUrl":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","width":300,"height":106,"caption":"Compartilha Bahia"},"image":{"@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/compartilhabahia","https:\/\/www.instagram.com\/compartilhabahia\/"]},{"@type":"Person","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/compartilhabahia.com.br"],"url":"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/"}]}},"_links":{"self":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7908"}],"version-history":[{"count":2,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7908\/revisions"}],"predecessor-version":[{"id":7912,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7908\/revisions\/7912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/7909"}],"wp:attachment":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}