{"id":7872,"date":"2025-09-14T21:35:21","date_gmt":"2025-09-15T00:35:21","guid":{"rendered":"https:\/\/compartilhabahia.com.br\/?p=7872"},"modified":"2025-09-14T21:35:58","modified_gmt":"2025-09-15T00:35:58","slug":"vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao","status":"publish","type":"post","link":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/","title":{"rendered":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Antes de Cama\u00e7ari ganhar avenidas e abrigar o maior Complexo Industrial Integrado do Hemisf\u00e9rio Sul, o distrito de Vila de Abrantes j\u00e1 tra\u00e7ava as primeiras linhas na hist\u00f3ria da cidade. Na tarde deste domingo (14), a localidade se encheu de cores e sentimentos c\u00edvicos para comemorar os 267 anos de emancipa\u00e7\u00e3o pol\u00edtica do munic\u00edpio, celebrado no pr\u00f3ximo dia 28 de setembro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787760940_a0e773135a_c.jpg\" alt=\"\" class=\"wp-image-7874\" style=\"width:674px;height:auto\" srcset=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787760940_a0e773135a_c.jpg 800w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787760940_a0e773135a_c-300x200.jpg 300w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787760940_a0e773135a_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Com as arquibancadas lotadas e os entornos da Rua Vieira de Melo repletos de pessoas, o tradicional desfile c\u00edvico-cultural come\u00e7ou com o pelot\u00e3o de bandeiras do Brasil, da Bahia e de Cama\u00e7ari. Na sequ\u00eancia, a Filarm\u00f4nica 28 de Setembro deu o tom musical ao cortejo celebrativo, seguido pela marcha sincronizada do Batalh\u00e3o do Tiro de Guerra, da Pol\u00edcia Militar, Defesa Civil e do grupo Desbravadores.<\/p>\n\n\n\n<p>\u201cCama\u00e7ari \u00e9 marcada por pessoas apaixonadas por esta terra. O desfile mostra a alma viva da popula\u00e7\u00e3o, representada pelas crian\u00e7as, pelos jovens, nos movimentos culturais, nos estudantes, em tudo\u201d, enfatizou o prefeito Luiz Caetano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-1024x682.jpg\" alt=\"\" class=\"wp-image-7875\" style=\"width:676px;height:auto\" srcset=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-1024x682.jpg 1024w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-300x200.jpg 300w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-768x512.jpg 768w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-1536x1023.jpg 1536w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h-1200x800.jpg 1200w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678068_61e5355e52_h.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Sob organiza\u00e7\u00e3o da Secretaria de Educa\u00e7\u00e3o (Seduc), o desfile trouxe o tema \u201cCama\u00e7ari Educadora: cuidados que inspiram e reconectam pessoas\u201d. Estudantes e educadores de sete escolas da rede p\u00fablica municipal brilharam na avenida, a exemplo da Creche Comunit\u00e1ria Senhora Sant\u2019Ana, localizada na Rua Jo\u00e3o Ara\u00fajo.<\/p>\n\n\n\n<p>\u201cNossa cidade \u00e9 rica em praias e belezas naturais, por isso, para este ano trouxemos o cuidado com a natureza como base para nossa apresenta\u00e7\u00e3o, mostrando aos nossos pequenos e a toda comunidade a import\u00e2ncia de cuidar do nosso patrim\u00f4nio\u201d, compartilhou Janete Almeida, diretora da Creche Senhora Sant\u2019Ana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787761075_855e072b0d_c.jpg\" alt=\"\" class=\"wp-image-7876\" srcset=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787761075_855e072b0d_c.jpg 800w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787761075_855e072b0d_c-300x200.jpg 300w, https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787761075_855e072b0d_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>M\u00e1rcio Neves, titular da Seduc, definiu o desfile como uma celebra\u00e7\u00e3o que honra o passado e valoriza o futuro. \u201c\u00c9 uma festa marcada pela pluralidade. Aqui integramos a comunidade com as escolas, as bandas, os grupos culturais e os artistas, para afirmar que a educa\u00e7\u00e3o \u00e9 o pilar essencial na valoriza\u00e7\u00e3o e propaga\u00e7\u00e3o da nossa hist\u00f3ria\u201d, pontuou o secret\u00e1rio.<\/p>\n\n\n\n<p>O desfile c\u00edvico tamb\u00e9m contou com a energia da Banda Marcial do Centro de Educa\u00e7\u00e3o Municipal de Cama\u00e7ari (Bamcemc), Fanfarra Estudantil de Parafuso (Fanesp), Banda Marcial Joana Ang\u00e9lica (Bamaja), Banda Municipal de Cama\u00e7ari (Bamuca), Art\u2019Vila, Banda Marcial de Vila de Abrantes (Fanesva) e da Fanfarra Municipal Popular de Vila de Abrantes (Fampa).<\/p>\n\n\n\n<p>Outro destaque na programa\u00e7\u00e3o foi o protagonismo dos grupos culturais Boi Bonito, Capoeira Engenho, Gr\u00e3o de Areia e da Cia de Dan\u00e7a Livre Dance, bem como da turma do Instituto Social D\u2019 Joana, que transformaram a Rua Vieira de Melo em um verdadeiro palco de identidade e resist\u00eancia.<\/p>\n\n\n\n<p>\u201cAtuamos h\u00e1 quatro anos em Areias, em conjunto com as escolas. S\u00e3o 160 crian\u00e7as e adolescentes falando de hist\u00f3ria por meio da m\u00fasica\u201d, revelou a idealizadora do Instituto D\u2019Joana, Lidiane Boa Morte. Para o desfile c\u00edvico deste domingo, o repert\u00f3rio resgatou as ra\u00edzes ancestrais. \u201cCama\u00e7ari tem forma\u00e7\u00e3o quilombola e ind\u00edgena. Nosso trabalho tamb\u00e9m visa ampliar essa sonoridade t\u00e3o marcante na cidade\u201d, acrescentou a professora de percuss\u00e3o e canto, Elaine Paranhos.<\/p>\n\n\n\n<p>Entre os moradores, a alegria de ver a tradi\u00e7\u00e3o seguir adiante, abra\u00e7ando todas as idades. \u201cSempre venho assistir os desfiles. Hoje, vi a gera\u00e7\u00e3o crescendo por meio do filho de uns amigos que estuda no Col\u00e9gio Estadual Nadir Ara\u00fajo e que se apresentou. Est\u00e1 tudo muito bonito e organizado. Espero que esse evento s\u00f3 cres\u00e7a a cada ano\u201d, endossou a moradora Francisca Franco, 61 anos.<\/p>\n\n\n\n<p>Para Stephanie Evangelista, 17 anos, o desfile deste ano representa um novo sentimento: o de estar na plateia, prestigiando os familiares. \u201cSempre desfilei e a emo\u00e7\u00e3o era enorme. Esse ano n\u00e3o fui para as ruas, mas pude ver a minha prima se apresentar. Ela toca trompete na Fampa\u201d, contou a jovem.<\/p>\n\n\n\n<p>O desfile em Vila de Abrantes \u00e9 parte da s\u00e9rie de atos c\u00edvicos que antecede a data magna do anivers\u00e1rio da cidade, com a realiza\u00e7\u00e3o do evento na Avenida 28 de Setembro (antiga Radial A), sede do munic\u00edpio.<\/p>\n\n\n\n<p>Foto: Juliano Sarraf, Patrick Abreu e William Rocha<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Segundo relatos hist\u00f3ricos, fundada h\u00e1 267 anos, Vila de Abrantes existiu como cidade por 180 anos,  passando posteriormente em 1938 o t\u00edtulo de Munic\u00edpio para  Cama\u00e7ari, que herdou tamb\u00e9m, al\u00e9m das responsabilidades administrativas, a longevidade de Abrantes, e por isso, de forma tradicional, comemora este ano, o seu 267\u00ba anivers\u00e1rio.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de Cama\u00e7ari ganhar avenidas e abrigar o maior Complexo Industrial Integrado do Hemisf\u00e9rio Sul, o distrito de Vila de Abrantes j\u00e1 tra\u00e7ava as primeiras linhas na hist\u00f3ria da cidade. Na tarde deste domingo (14), a localidade se encheu de cores e sentimentos c\u00edvicos para comemorar os 267 anos de emancipa\u00e7\u00e3o pol\u00edtica do munic\u00edpio, celebrado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-7872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-camacari"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia\" \/>\n<meta property=\"og:description\" content=\"Antes de Cama\u00e7ari ganhar avenidas e abrigar o maior Complexo Industrial Integrado do Hemisf\u00e9rio Sul, o distrito de Vila de Abrantes j\u00e1 tra\u00e7ava as primeiras linhas na hist\u00f3ria da cidade. Na tarde deste domingo (14), a localidade se encheu de cores e sentimentos c\u00edvicos para comemorar os 267 anos de emancipa\u00e7\u00e3o pol\u00edtica do munic\u00edpio, celebrado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Compartilha Bahia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/compartilhabahia\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-15T00:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-15T00:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678263_14a6640716_h.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\"},\"headline\":\"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o\",\"datePublished\":\"2025-09-15T00:35:21+00:00\",\"dateModified\":\"2025-09-15T00:35:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\"},\"wordCount\":775,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"articleSection\":[\"Cama\u00e7ari\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\",\"name\":\"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia\",\"isPartOf\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\"},\"datePublished\":\"2025-09-15T00:35:21+00:00\",\"dateModified\":\"2025-09-15T00:35:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/compartilhabahia.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#website\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"name\":\"Compartilha Bahia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/compartilhabahia.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#organization\",\"name\":\"Compartilha Bahia\",\"url\":\"https:\/\/compartilhabahia.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"contentUrl\":\"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png\",\"width\":300,\"height\":106,\"caption\":\"Compartilha Bahia\"},\"image\":{\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/compartilhabahia\",\"https:\/\/www.instagram.com\/compartilhabahia\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/compartilhabahia.com.br\"],\"url\":\"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia","og_description":"Antes de Cama\u00e7ari ganhar avenidas e abrigar o maior Complexo Industrial Integrado do Hemisf\u00e9rio Sul, o distrito de Vila de Abrantes j\u00e1 tra\u00e7ava as primeiras linhas na hist\u00f3ria da cidade. Na tarde deste domingo (14), a localidade se encheu de cores e sentimentos c\u00edvicos para comemorar os 267 anos de emancipa\u00e7\u00e3o pol\u00edtica do munic\u00edpio, celebrado [&hellip;]","og_url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/","og_site_name":"Compartilha Bahia","article_publisher":"https:\/\/web.facebook.com\/compartilhabahia","article_published_time":"2025-09-15T00:35:21+00:00","article_modified_time":"2025-09-15T00:35:58+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2025\/09\/54787678263_14a6640716_h.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#article","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/"},"author":{"name":"admin","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04"},"headline":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o","datePublished":"2025-09-15T00:35:21+00:00","dateModified":"2025-09-15T00:35:58+00:00","mainEntityOfPage":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/"},"wordCount":775,"commentCount":0,"publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"articleSection":["Cama\u00e7ari"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/","url":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/","name":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o - Compartilha Bahia","isPartOf":{"@id":"https:\/\/compartilhabahia.com.br\/#website"},"datePublished":"2025-09-15T00:35:21+00:00","dateModified":"2025-09-15T00:35:58+00:00","breadcrumb":{"@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/compartilhabahia.com.br\/index.php\/2025\/09\/14\/vila-de-abrantes-comemora-267-anos-de-camacari-com-desfile-repleto-de-tradicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/compartilhabahia.com.br\/"},{"@type":"ListItem","position":2,"name":"Vila de Abrantes comemora 267 anos de Cama\u00e7ari com desfile repleto de tradi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/compartilhabahia.com.br\/#website","url":"https:\/\/compartilhabahia.com.br\/","name":"Compartilha Bahia","description":"","publisher":{"@id":"https:\/\/compartilhabahia.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/compartilhabahia.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/compartilhabahia.com.br\/#organization","name":"Compartilha Bahia","url":"https:\/\/compartilhabahia.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","contentUrl":"https:\/\/compartilhabahia.com.br\/wp-content\/uploads\/2023\/12\/cropped-logo.png","width":300,"height":106,"caption":"Compartilha Bahia"},"image":{"@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/compartilhabahia","https:\/\/www.instagram.com\/compartilhabahia\/"]},{"@type":"Person","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/9b4f0c3178793b8248d6686732521c04","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/compartilhabahia.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9600df58751c5acbe914c538c03390ef649ea088cb65f84ba09c7ce66988eed6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/compartilhabahia.com.br"],"url":"https:\/\/compartilhabahia.com.br\/index.php\/author\/compartilhabahia\/"}]}},"_links":{"self":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7872"}],"version-history":[{"count":1,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7872\/revisions"}],"predecessor-version":[{"id":7877,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7872\/revisions\/7877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media\/7873"}],"wp:attachment":[{"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/compartilhabahia.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}